{"id":5749,"date":"2026-07-23T11:48:50","date_gmt":"2026-07-23T15:48:50","guid":{"rendered":"https:\/\/consfiladelfia.esteri.it\/?p=5749"},"modified":"2026-08-31T11:20:21","modified_gmt":"2026-08-31T15:20:21","slug":"elezioni-com-it-es-2026","status":"publish","type":"post","link":"https:\/\/consfiladelfia.esteri.it\/it\/news\/dal_consolato\/2026\/07\/elezioni-com-it-es-2026\/","title":{"rendered":"Elezioni Com.It.Es. 2026"},"content":{"rendered":"<p>Quest\u2019anno si terranno le elezioni per il rinnovo dei Com.It.Es.. Gli italiani residenti all\u2019estero che ne faranno richiesta, saranno chiamati a votare.<\/p>\n<p><strong>Per cosa si vota?<br \/>\n<\/strong>Si vota per il rinnovo dei Comitati degli Italiani all\u2019Estero.<br \/>\nIstituiti nel 1985, i Com.It.Es. sono organismi rappresentativi della collettivit\u00e0 italiana all\u2019estero eletti direttamente dai connazionali residenti da almeno 6 mesi nella Circoscrizione Consolare di appartenenza.<\/p>\n<p><strong>Cosa fanno i Com.It.Es.?<br \/>\n<\/strong>Rappresentano i connazionali all\u2019estero nei rapporti con Ambasciate e Consolati e ne favoriscono l\u2019integrazione.<br \/>\nHanno altres\u00ec il compito di preservare la memoria storica dell\u2019emigrazione italiana e valorizzare il contributo italiano nelle societ\u00e0 in cui operano.<\/p>\n<p><strong>Quando si formano e da chi sono composti?<br \/>\n<\/strong>I Com.It.Es. possono essere istituiti nelle Circoscrizioni consolari che superano i 3.000 iscritti AIRE e sono composti da 12 membri nelle comunit\u00e0 fino a 100.000 connazionali e da 18 membri nelle comunit\u00e0 che superano tale soglia.<br \/>\nI membri dei comitati restano in carica 5 anni.<\/p>\n<p><strong>Chi pu\u00f2 votare alle elezioni dei Com.It.Es.?<br \/>\n<\/strong>I connazionali residenti da almeno 6 mesi nella Circoscrizione consolare che abbiano inviato al Consolato di appartenenza apposita domanda di iscrizione nell\u2019elenco degli elettori.<\/p>\n<p><strong>Come si vota?<br \/>\n<\/strong>Il voto per le elezioni dei Com.It.Es. avviene per corrispondenza.<br \/>\nLe schede verranno inviate all\u2019indirizzo di residenza di coloro che ne abbiano fatto richiesta.<br \/>\nSuccessivamente, dovranno essere rispedite alla Concelleria Consolare presso l\u2019Ambasciata di Italia di Washington o al proprio Consolato di riferimento, seguendo attentamente le indicazioni del foglio informativo presenti nel plico elettorale.<\/p>\n<p>Per maggiori informazioni sulle elezioni visita il sito della Farnesina a questa pagina web:<br \/>\n<a href=\"https:\/\/www.esteri.it\/it\/sala_stampa\/archivionotizie\/eventi\/2026\/07\/elezionidei-comites-2026\/\">https:\/\/www.esteri.it\/it\/sala_stampa\/archivionotizie\/eventi\/2026\/07\/elezionidei-comites-2026\/<\/a><\/p>\n<p>Per maggiori informazioni sul ruolo e le attivita\u2019 dei Com.It.Es. visita\u00a0<a href=\"https:\/\/www.esteri.it\/it\/servizi-opportunita\/italiani-all-estero\/organismirappresentativi\/comites\/\">questa pagina<\/a>\u00a0sul sito della Farnesina.<\/p>\n<p><strong><u>MODALITA\u2019 PER LA RICHIESTA DI ISCRIZIONE NELL\u2019ELENCO ELETTORALE<\/u><\/strong><\/p>\n<p>Le elezioni per il rinnovo e l\u2019istituzione dei COMITES si terranno\u00a0<u>entro la fine del 2026<\/u>.<\/p>\n<p>I Comitati degli italiani all\u2019estero sono organi di rappresentanza della collettivit\u00e0 italiana nei rapporti con le rappresentanze diplomatico-consolari e operano per l\u2019integrazione della comunit\u00e0 italiana residente nel Paese straniero in cui si trovano.<\/p>\n<p>A questo importante appuntamento elettorale potranno partecipare gli\u00a0<strong>elettori<\/strong>, in possesso dei requisiti di legge per l\u2019elettorato attivo,\u00a0<strong>residenti e iscritti all\u2019AIRE nella circoscrizione consolare da almeno 6 MESI<\/strong>\u00a0<strong>(rispetto alla data delle elezioni)<\/strong>.<\/p>\n<p>Il voto si svolge per corrispondenza, ma \u2013 a differenza delle elezioni politiche e dei referendum \u2013 il plico elettorale viene spedito SOLTANTO agli elettori che abbiano presentato espressa richiesta di iscrizione nell\u2019elenco elettorale per le elezioni dei Com.It.Es. entro il 4 novembre 2026.<\/p>\n<div class=\"responsive\">\n<table class=\"table table-bordered table-sm export-table\">\n<tbody>\n<tr class=\"thead-light\">\n<td width=\"642\"><strong>ATTENZIONE:\u00a0<\/strong>per ricevere il plico elettorale l\u2019elettore deve quindi richiedere al proprio consolato di riferimento di essere iscritto nell\u2019elenco elettorale,<strong>\u00a0<u>ENTRO E NON OLTRE IL 4 NOVEMBRE 2026<\/u>.<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Il cittadino potr\u00e0 far pervenire il <strong><a href=\"https:\/\/consfiladelfia.esteri.it\/wp-content\/uploads\/2026\/08\/5.1-Allegato-1-Modello-opzione-inversa.pdf\">modulo<\/a>\u00a0<\/strong>per l\u2019iscrizione nell\u2019elenco elettorale per le elezioni dei Com.It.Es. in uno dei seguenti modi:<\/p>\n<\/div>\n<ul>\n<li>consegnandolo di persona (previo appuntamento, ove richiesto \u2013 presentarsi muniti di un documento di identit\u00e0);<\/li>\n<li>inviandolo per posta cartacea insieme a fotocopia di un documento di identit\u00e0 comprensivo della firma del titolare al seguente indirizzo: <strong>Consolato Generale d&#8217;Italia &#8211; attenzione ufficio elettorale &#8211; 1818 Market street, suite 910 &#8211; Philadelphia PA 19103<\/strong>;<\/li>\n<li>inviandolo per posta elettronica ordinaria (<strong>elettorale.filadelfia@esteri.it<\/strong>), insieme a copia del documento d\u2019identit\u00e0, comprensivo della firma del titolare.<\/li>\n<\/ul>\n<p><span style=\"text-decoration: underline;\"><strong>ELEZIONI COM.IT.ES. 2026 &#8211; <\/strong><strong>PREDISPOSIZIONE E PRESENTAZIONE LISTE ELETTORALI<\/strong><\/span><\/p>\n<p>Entro la fine del 2026 avranno luogo le elezioni per il rinnovo dei Comitati degli Italiani all\u2019Estero (Com.It.Es.).<\/p>\n<p>Ai sensi dell\u2019art. 14 del DPR 395\/2003, le liste possono essere <strong>presentate all\u2019Ufficio elettorale<\/strong> nelle ore d\u2019ufficio <strong><u>dal ventesimo al trentesimo giorno successivo all\u2019indizione<\/u><\/strong>.<\/p>\n<p>La raccolta delle firme, la sottoscrizione delle liste e le relative autentiche possono avvenire sin da ora.<\/p>\n<p>Le liste sono formate da un numero di candidati almeno pari al numero dei membri del Comitato da eleggere e non superiore a 16 per i Com.It.Es. composti da 12 membri o 22 per i Com.It.Es. composti da 18 membri. (DPR 395\/2003, art 14, co 2).<\/p>\n<p>Le liste, ciascuna munita del proprio contrassegno, sono presentate da uno dei candidati o da un sottoscrittore. Il presentatore della lista dichiara il proprio domicilio ai fini delle successive notificazioni.<\/p>\n<p><strong>Requisiti<\/strong><\/p>\n<p>Ai sensi del DPR 395\/2003 art 16, la candidatura <strong><em>non \u00e8 ammessa<\/em><\/strong>:<\/p>\n<ul>\n<li>quando il candidato \u00e8 minorenne;<\/li>\n<li>quando la candidatura \u00e8 presentata per pi\u00f9 liste;<\/li>\n<li>quando il candidato non \u00e8 residente nella circoscrizione consolare;<\/li>\n<li>quando manca la dichiarazione di accettazione della candidatura.<\/li>\n<\/ul>\n<p>Ai sensi del DPR 395\/2003, art 6, sono <strong><em>eleggibili<\/em><\/strong> i cittadini italiani:<\/p>\n<ul>\n<li>residenti nella circoscrizione consolare;<\/li>\n<li>candidati in una (e in una sola) delle liste presentate (e in una sola circoscrizione);<\/li>\n<li>iscritti nell\u2019elenco aggiornato di cui all\u2019art. 5 comma 1 della Legge 459\/2001;<\/li>\n<li>in possesso dei requisiti per essere candidati alle consultazioni elettorali amministrative, ovvero i requisiti previsti dall\u2019articolo 55 (Elettorato passivo), comma 1, del D.lgs. 267\/2000, ovvero aver compiuto il diciottesimo anno di et\u00e0, nel giorno fissato per la votazione<\/li>\n<\/ul>\n<p><strong><em>Non sono eleggibili<\/em><\/strong>:<\/p>\n<ul>\n<li>i dipendenti dello Stato italiano che prestano servizio all\u2019estero, ivi compresi il personale a contratto;<\/li>\n<li>coloro che detengono cariche istituzionali e i loro collaboratori salariati;<\/li>\n<li>gli amministratori e i legali rappresentanti (in base all\u2019atto costitutivo e allo statuto) di enti gestori di attivit\u00e0 scolastiche che operano nel territorio del Comitato;<\/li>\n<li>gli amministratori e i legali rappresentanti (in base all\u2019atto costitutivo e allo statuto) dei comitati per l\u2019assistenza che ricevono finanziamenti pubblici;<\/li>\n<li>coloro che sono indicati negli articoli 60 (Ineleggibilit\u00e0) e 61 (Ineleggibilit\u00e0 e incompatibilit\u00e0 alla carica di sindaco e presidente di provincia) del D.lgs. 267\/2000;<\/li>\n<li>coloro per cui ricorrono le condizioni previste dagli articoli 10 (Incandidabilit\u00e0 alle elezioni provinciali, comunali e circoscrizionali) e 11 (Sospensione e decadenza di diritto degli amministratori locali in condizione di incandidabilit\u00e0) del D.lgs. 235\/2012;<\/li>\n<li>coloro che sono stati gi\u00e0 componenti del medesimo Comitato per due mandati consecutivi.<\/li>\n<\/ul>\n<p><strong>Documentazione<\/strong><\/p>\n<p>Le dichiarazioni di presentazione delle liste dei candidati possono essere firmate in atti (fogli) separati. Gli atti separati di raccolta delle firme riportano il contrassegno di lista, nonch\u00e9 tutti i nominativi dei candidati.<\/p>\n<p>Ogni lista di candidati (ognuno con cognome, nome, luogo e data di nascita, nonch\u00e9 numero progressivo attribuito dal presentatore di lista) deve essere corredata della seguente documentazione:<\/p>\n<ol>\n<li><strong>le dichiarazioni di accettazione della candidatura <\/strong>da parte di ciascun candidato, firmate e autenticate (<a href=\"https:\/\/consfiladelfia.esteri.it\/wp-content\/uploads\/2026\/08\/ALLEGATO-1-Modulo-accettazione-candidatura.pdf\"><u>allegato 1<\/u><\/a>);<\/li>\n<li><strong>i certificati, anche collettivi, che attestano l\u2019iscrizione degli elettori nelle liste elettorali della relativa circoscrizione. <\/strong>Tali certificati sono rilasciati dall\u2019ufficio consolare su richiesta degli interessati e sulla base degli atti in possesso dell\u2019ufficio stesso, <strong><u>a partire dal quindicesimo giorno successivo alla data di indizione<\/u><\/strong> delle elezioni, nel termine improrogabile di ventiquattro ore dalla richiesta (DPR 395\/2003, art 14, co 8);<\/li>\n<li><strong>la designazione di un rappresentante effettivo e di uno supplente<\/strong> per il comitato elettorale circoscrizionale;<\/li>\n<li><strong>le sottoscrizioni prescritte dalla legge con le relative autentiche<\/strong>. Per ogni sottoscrittore la lista deve recare il cognome, il nome, il luogo, la data di nascita e la certificazione elettorale di cui al punto b). Le dichiarazioni di presentazionedelle liste possono essere firmate in atti (fogli) principali e separati <u>(<\/u><a href=\"https:\/\/consfiladelfia.esteri.it\/wp-content\/uploads\/2026\/08\/ALLEGATO-2-Modello_di_dichiarazione_di_presentazione_lista_candidati-A._.pdf\"><u>allegato 2<\/u><\/a> e <a href=\"https:\/\/consfiladelfia.esteri.it\/wp-content\/uploads\/2026\/08\/ALLEGATO-3-Modello_di_dichiarazione_di_presentazione_lista_candidati-A._.pdf\"><u>allegato 3<\/u><\/a>). Anche gli <strong>atti separati<\/strong> di raccolta delle firme devono riportare il contrassegno della lista, tutti i nominativi dei candidati e, aseguire, le sottoscrizioni.<\/li>\n<\/ol>\n<p>Si ricorda che ogni lista, munita di proprio contrassegno, \u00e8 presentata da uno dei candidati o da uno dei sottoscrittori all&#8217;ufficio elettorale, nelle ore d&#8217;ufficio, dal ventesimo al trentesimo giorno successivo alla data di indizione delle elezioni.<\/p>\n<p><strong>Sottoscrizioni e autentiche delle firme<\/strong><\/p>\n<p>Ai sensi della normativa vigente (Art.13, comma 1, Legge 286\/2003), i sottoscrittori delle liste devono essere <u>residenti nella circoscrizione<\/u> consolare da almeno <u>sei mesi<\/u> e risultare negli <u>elenchi elettori<\/u> per le elezioni dei Com.It.Es.. I sottoscrittori <strong>non possono essere candidati e non possono sottoscrivere pi\u00f9 di una lista, <\/strong><strong>pena la nullit\u00e0 della sottoscrizione.<\/strong><\/p>\n<p>L\u2019art. 15, comma 3, della L. 286\/2003 stabilisce che le liste di candidati sono sottoscritte da un numero di elettori:<\/p>\n<ul>\n<li>non inferiore a<strong> 100 <\/strong>per le collettivit\u00e0 composte da un numero di cittadini italiani residenti <strong>fino a<\/strong> <strong>000;<\/strong><\/li>\n<li>non inferiore a<strong> 200 <\/strong>per quelle composte da un numero <strong>superiore<\/strong> <strong>a 50.000<\/strong>.<\/li>\n<\/ul>\n<p>Per ogni sottoscrittore va indicato:<\/p>\n<ul>\n<li>cognome;<\/li>\n<li>nome;<\/li>\n<li>luogo e la data di nascita.<\/li>\n<\/ul>\n<p>Ai sensi della legislazione in vigore, <strong>le firme possono essere autenticate solo dagli Uffici consolari di I categoria<\/strong>, con esclusione quindi dei Consoli Onorari. L\u2019autentica \u00e8 sempre gratuita (art. 34 del DPR 395\/2003).<\/p>\n<p><strong>Al fine di agevolare la sottoscrizione delle liste elettorali Com.It.Es. e le relative operazioni di autenticazione da parte del Consolato, si mette a disposizione\u00a0 la sala conferenze della sede consolare (1818 Market Street, Suite 910, Philadelphia, PA 19103) dalle ore 14.00 alle ore 16.00 di gioved\u00ec 10 e venerd\u00ec 11 settembre 2026. <\/strong>In conformita\u2019 con le regole di accesso alla sede, si prega di informare questo Consolato con almeno un giorno i anticipo, scrivendo all\u2019indirizzo dedicato: <a href=\"mailto:elettorale.filadelfia@esteri.it\">elettorale.filadelfia@esteri.it<\/a>.<\/p>\n<p>Qualora gli interessati individuassero una sede\/diverso luogo neutro presso il quale riunire gli almeno 100 sottoscrittori necessari alla presentzione di una lista elettorale, la Sede consolare potra\u2019 altres\u00ec valutare l\u2019opportunita\u2019 di organizzare la presenza del proprio personale al fine di provvedere alle operazioni di autenticazione, in date da concordare preventivamente con l\u2019Ufficio Elettorale.<\/p>\n<p>Al momento della firma, il sottoscrittore dovr\u00e0 essere identificato tramite un documento di riconoscimento (passaporto o carta d\u2019identit\u00e0), purch\u00e9 munito di fotografia del titolare e rilasciato da una pubblica amministrazione italiana o di altri Stati.<\/p>\n<p>Nota: Per le donne coniugate occorre anche presentare un documento (esempio certificato di nascita o di matrimonio) attraverso cui si possa verificare il cognome da nubile.<\/p>\n","protected":false},"excerpt":{"rendered":"Quest\u2019anno si terranno le elezioni per il rinnovo dei Com.It.Es.. Gli italiani residenti all\u2019estero che ne faranno richiesta, saranno chiamati a votare. Per cosa si vota? Si vota per il rinnovo dei Comitati degli Italiani all\u2019Estero. Istituiti nel 1985, i Com.It.Es. sono organismi rappresentativi della collettivit\u00e0 italiana all\u2019estero eletti direttamente dai connazionali residenti da almeno [&hellip;]","protected":false},"author":3,"featured_media":5752,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"tags":[],"class_list":["post-5749","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/consfiladelfia.esteri.it\/it\/wp-json\/wp\/v2\/posts\/5749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/consfiladelfia.esteri.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/consfiladelfia.esteri.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/consfiladelfia.esteri.it\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/consfiladelfia.esteri.it\/it\/wp-json\/wp\/v2\/comments?post=5749"}],"version-history":[{"count":6,"href":"https:\/\/consfiladelfia.esteri.it\/it\/wp-json\/wp\/v2\/posts\/5749\/revisions"}],"predecessor-version":[{"id":5876,"href":"https:\/\/consfiladelfia.esteri.it\/it\/wp-json\/wp\/v2\/posts\/5749\/revisions\/5876"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/consfiladelfia.esteri.it\/it\/wp-json\/wp\/v2\/media\/5752"}],"wp:attachment":[{"href":"https:\/\/consfiladelfia.esteri.it\/it\/wp-json\/wp\/v2\/media?parent=5749"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/consfiladelfia.esteri.it\/it\/wp-json\/wp\/v2\/tags?post=5749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}